{"id":2494,"date":"2020-12-15T23:20:13","date_gmt":"2020-12-15T22:20:13","guid":{"rendered":"https:\/\/www.bettinakletzsch.de\/en\/?p=2494"},"modified":"2021-02-25T09:03:23","modified_gmt":"2021-02-25T08:03:23","slug":"cold-days-need-warm-socks","status":"publish","type":"post","link":"https:\/\/www.bettinakletzsch.de\/en\/2020\/12\/15\/cold-days-need-warm-socks\/","title":{"rendered":"Cold days need warm socks"},"content":{"rendered":"\n<figure class=\"wp-block-video\"><video height=\"1080\" style=\"aspect-ratio: 1920 \/ 1080;\" width=\"1920\" controls poster=\"https:\/\/www.bettinakletzsch.de\/wordpress\/wp-content\/uploads\/2020\/12\/Bildschirmfoto-2020-12-15-um-23.29.46-1.png\" src=\"https:\/\/www.bettinakletzsch.de\/wordpress\/wp-content\/uploads\/2020\/12\/die-socke-brennt_1.mp4\"><\/video><figcaption>Idee und Video: Bettina Kletzsch &#038; Konrad Behr <\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Instalation im ETWAS 1 und ETWAS 2 in Augustusburg\/ Erzgebierge.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Instalation im ETWAS 1 und ETWAS 2 in Augustusburg\/ Erzgebierge.<\/p>\n","protected":false},"author":3,"featured_media":2518,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"h5ap_radio_sources":[],"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1,4],"tags":[8],"class_list":["post-2494","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-projekte","tag-ausstellung"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cold days need warm socks<\/title>\n<meta name=\"description\" content=\"Bettina Kletzsch -\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bettinakletzsch.de\/en\/2020\/12\/15\/cold-days-need-warm-socks\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:locale:alternate\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cold days need warm socks\" \/>\n<meta property=\"og:description\" content=\"Bettina Kletzsch -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bettinakletzsch.de\/en\/2020\/12\/15\/cold-days-need-warm-socks\/\" \/>\n<meta property=\"og:site_name\" content=\"Bettina Kletzsch\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-15T22:20:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-25T08:03:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i1.wp.com\/www.bettinakletzsch.de\/wordpress\/wp-content\/uploads\/2020\/12\/Bildschirmfoto-2020-12-16-um-00.01.14.png?fit=1920%2C1200&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Bettina Kletzsch\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bettina Kletzsch\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.bettinakletzsch.de\\\/2020\\\/12\\\/15\\\/cold-days-need-warm-socks\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bettinakletzsch.de\\\/2020\\\/12\\\/15\\\/cold-days-need-warm-socks\\\/\"},\"author\":{\"name\":\"Bettina Kletzsch\",\"@id\":\"https:\\\/\\\/www.bettinakletzsch.de\\\/en\\\/#\\\/schema\\\/person\\\/af10bb2613a2a417ba43501dd0db767e\"},\"headline\":\"Cold days need warm socks\",\"datePublished\":\"2020-12-15T22:20:13+00:00\",\"dateModified\":\"2021-02-25T08:03:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.bettinakletzsch.de\\\/2020\\\/12\\\/15\\\/cold-days-need-warm-socks\\\/\"},\"wordCount\":50,\"publisher\":{\"@id\":\"https:\\\/\\\/www.bettinakletzsch.de\\\/en\\\/#\\\/schema\\\/person\\\/af10bb2613a2a417ba43501dd0db767e\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bettinakletzsch.de\\\/2020\\\/12\\\/15\\\/cold-days-need-warm-socks\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.bettinakletzsch.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Bildschirmfoto-2020-12-16-um-00.01.14.png?fit=1920%2C1200&ssl=1\",\"keywords\":[\"Exhibition\"],\"articleSection\":[\"News\",\"Projects\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bettinakletzsch.de\\\/2020\\\/12\\\/15\\\/cold-days-need-warm-socks\\\/\",\"url\":\"https:\\\/\\\/www.bettinakletzsch.de\\\/2020\\\/12\\\/15\\\/cold-days-need-warm-socks\\\/\",\"name\":\"Cold days need warm socks\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bettinakletzsch.de\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bettinakletzsch.de\\\/2020\\\/12\\\/15\\\/cold-days-need-warm-socks\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bettinakletzsch.de\\\/2020\\\/12\\\/15\\\/cold-days-need-warm-socks\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.bettinakletzsch.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Bildschirmfoto-2020-12-16-um-00.01.14.png?fit=1920%2C1200&ssl=1\",\"datePublished\":\"2020-12-15T22:20:13+00:00\",\"dateModified\":\"2021-02-25T08:03:23+00:00\",\"description\":\"Bettina Kletzsch -\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bettinakletzsch.de\\\/2020\\\/12\\\/15\\\/cold-days-need-warm-socks\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bettinakletzsch.de\\\/2020\\\/12\\\/15\\\/cold-days-need-warm-socks\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.bettinakletzsch.de\\\/2020\\\/12\\\/15\\\/cold-days-need-warm-socks\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.bettinakletzsch.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Bildschirmfoto-2020-12-16-um-00.01.14.png?fit=1920%2C1200&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.bettinakletzsch.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Bildschirmfoto-2020-12-16-um-00.01.14.png?fit=1920%2C1200&ssl=1\",\"width\":1920,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bettinakletzsch.de\\\/2020\\\/12\\\/15\\\/cold-days-need-warm-socks\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.bettinakletzsch.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kalte Tage brauchen warme socken\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bettinakletzsch.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.bettinakletzsch.de\\\/en\\\/\",\"name\":\"Bettina Kletzsch\",\"description\":\"Mixed Mode\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.bettinakletzsch.de\\\/en\\\/#\\\/schema\\\/person\\\/af10bb2613a2a417ba43501dd0db767e\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bettinakletzsch.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.bettinakletzsch.de\\\/en\\\/#\\\/schema\\\/person\\\/af10bb2613a2a417ba43501dd0db767e\",\"name\":\"Bettina Kletzsch\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/i2.wp.com\\\/www.bettinakletzsch.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Konfektionshaus_Regenbogen_reduziert_gedreht-1.jpg?fit=827%2C827&ssl=1\",\"url\":\"https:\\\/\\\/i2.wp.com\\\/www.bettinakletzsch.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Konfektionshaus_Regenbogen_reduziert_gedreht-1.jpg?fit=827%2C827&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i2.wp.com\\\/www.bettinakletzsch.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Konfektionshaus_Regenbogen_reduziert_gedreht-1.jpg?fit=827%2C827&ssl=1\",\"width\":827,\"height\":827,\"caption\":\"Bettina Kletzsch\"},\"logo\":{\"@id\":\"https:\\\/\\\/i2.wp.com\\\/www.bettinakletzsch.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Konfektionshaus_Regenbogen_reduziert_gedreht-1.jpg?fit=827%2C827&ssl=1\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cold days need warm socks","description":"Bettina Kletzsch -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bettinakletzsch.de\/en\/2020\/12\/15\/cold-days-need-warm-socks\/","og_locale":"en_US","og_type":"article","og_title":"[:de]Kalte Tage brauchen warme socken[:en]Cold days need warm socks[:] - Bettina Kletzsch","og_description":"Bettina Kletzsch -","og_url":"https:\/\/www.bettinakletzsch.de\/en\/2020\/12\/15\/cold-days-need-warm-socks\/","og_site_name":"Bettina Kletzsch","article_published_time":"2020-12-15T22:20:13+00:00","article_modified_time":"2021-02-25T08:03:23+00:00","og_image":[{"width":1920,"height":1200,"url":"https:\/\/i1.wp.com\/www.bettinakletzsch.de\/wordpress\/wp-content\/uploads\/2020\/12\/Bildschirmfoto-2020-12-16-um-00.01.14.png?fit=1920%2C1200&ssl=1","type":"image\/png"}],"author":"Bettina Kletzsch","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Bettina Kletzsch"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.bettinakletzsch.de\/2020\/12\/15\/cold-days-need-warm-socks\/#article","isPartOf":{"@id":"https:\/\/www.bettinakletzsch.de\/2020\/12\/15\/cold-days-need-warm-socks\/"},"author":{"name":"Bettina Kletzsch","@id":"https:\/\/www.bettinakletzsch.de\/en\/#\/schema\/person\/af10bb2613a2a417ba43501dd0db767e"},"headline":"Cold days need warm socks","datePublished":"2020-12-15T22:20:13+00:00","dateModified":"2021-02-25T08:03:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.bettinakletzsch.de\/2020\/12\/15\/cold-days-need-warm-socks\/"},"wordCount":50,"publisher":{"@id":"https:\/\/www.bettinakletzsch.de\/en\/#\/schema\/person\/af10bb2613a2a417ba43501dd0db767e"},"image":{"@id":"https:\/\/www.bettinakletzsch.de\/2020\/12\/15\/cold-days-need-warm-socks\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.bettinakletzsch.de\/wordpress\/wp-content\/uploads\/2020\/12\/Bildschirmfoto-2020-12-16-um-00.01.14.png?fit=1920%2C1200&ssl=1","keywords":["Exhibition"],"articleSection":["News","Projects"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.bettinakletzsch.de\/2020\/12\/15\/cold-days-need-warm-socks\/","url":"https:\/\/www.bettinakletzsch.de\/2020\/12\/15\/cold-days-need-warm-socks\/","name":"Cold days need warm socks","isPartOf":{"@id":"https:\/\/www.bettinakletzsch.de\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bettinakletzsch.de\/2020\/12\/15\/cold-days-need-warm-socks\/#primaryimage"},"image":{"@id":"https:\/\/www.bettinakletzsch.de\/2020\/12\/15\/cold-days-need-warm-socks\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.bettinakletzsch.de\/wordpress\/wp-content\/uploads\/2020\/12\/Bildschirmfoto-2020-12-16-um-00.01.14.png?fit=1920%2C1200&ssl=1","datePublished":"2020-12-15T22:20:13+00:00","dateModified":"2021-02-25T08:03:23+00:00","description":"Bettina Kletzsch -","breadcrumb":{"@id":"https:\/\/www.bettinakletzsch.de\/2020\/12\/15\/cold-days-need-warm-socks\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bettinakletzsch.de\/2020\/12\/15\/cold-days-need-warm-socks\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.bettinakletzsch.de\/2020\/12\/15\/cold-days-need-warm-socks\/#primaryimage","url":"https:\/\/i0.wp.com\/www.bettinakletzsch.de\/wordpress\/wp-content\/uploads\/2020\/12\/Bildschirmfoto-2020-12-16-um-00.01.14.png?fit=1920%2C1200&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.bettinakletzsch.de\/wordpress\/wp-content\/uploads\/2020\/12\/Bildschirmfoto-2020-12-16-um-00.01.14.png?fit=1920%2C1200&ssl=1","width":1920,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.bettinakletzsch.de\/2020\/12\/15\/cold-days-need-warm-socks\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.bettinakletzsch.de\/"},{"@type":"ListItem","position":2,"name":"Kalte Tage brauchen warme socken"}]},{"@type":"WebSite","@id":"https:\/\/www.bettinakletzsch.de\/en\/#website","url":"https:\/\/www.bettinakletzsch.de\/en\/","name":"Bettina Kletzsch","description":"Mixed Mode","publisher":{"@id":"https:\/\/www.bettinakletzsch.de\/en\/#\/schema\/person\/af10bb2613a2a417ba43501dd0db767e"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bettinakletzsch.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/www.bettinakletzsch.de\/en\/#\/schema\/person\/af10bb2613a2a417ba43501dd0db767e","name":"Bettina Kletzsch","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/i2.wp.com\/www.bettinakletzsch.de\/wordpress\/wp-content\/uploads\/2020\/04\/Konfektionshaus_Regenbogen_reduziert_gedreht-1.jpg?fit=827%2C827&ssl=1","url":"https:\/\/i2.wp.com\/www.bettinakletzsch.de\/wordpress\/wp-content\/uploads\/2020\/04\/Konfektionshaus_Regenbogen_reduziert_gedreht-1.jpg?fit=827%2C827&ssl=1","contentUrl":"https:\/\/i2.wp.com\/www.bettinakletzsch.de\/wordpress\/wp-content\/uploads\/2020\/04\/Konfektionshaus_Regenbogen_reduziert_gedreht-1.jpg?fit=827%2C827&ssl=1","width":827,"height":827,"caption":"Bettina Kletzsch"},"logo":{"@id":"https:\/\/i2.wp.com\/www.bettinakletzsch.de\/wordpress\/wp-content\/uploads\/2020\/04\/Konfektionshaus_Regenbogen_reduziert_gedreht-1.jpg?fit=827%2C827&ssl=1"}}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.bettinakletzsch.de\/wordpress\/wp-content\/uploads\/2020\/12\/Bildschirmfoto-2020-12-16-um-00.01.14.png?fit=1920%2C1200&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.bettinakletzsch.de\/en\/wp-json\/wp\/v2\/posts\/2494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bettinakletzsch.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bettinakletzsch.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bettinakletzsch.de\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bettinakletzsch.de\/en\/wp-json\/wp\/v2\/comments?post=2494"}],"version-history":[{"count":10,"href":"https:\/\/www.bettinakletzsch.de\/en\/wp-json\/wp\/v2\/posts\/2494\/revisions"}],"predecessor-version":[{"id":2609,"href":"https:\/\/www.bettinakletzsch.de\/en\/wp-json\/wp\/v2\/posts\/2494\/revisions\/2609"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bettinakletzsch.de\/en\/wp-json\/wp\/v2\/media\/2518"}],"wp:attachment":[{"href":"https:\/\/www.bettinakletzsch.de\/en\/wp-json\/wp\/v2\/media?parent=2494"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bettinakletzsch.de\/en\/wp-json\/wp\/v2\/categories?post=2494"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bettinakletzsch.de\/en\/wp-json\/wp\/v2\/tags?post=2494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}